{"id":3625,"date":"2020-12-28T15:35:02","date_gmt":"2020-12-28T14:35:02","guid":{"rendered":"https:\/\/visium360.fr\/?page_id=3625"},"modified":"2025-10-21T15:30:32","modified_gmt":"2025-10-21T13:30:32","slug":"notre-plateforme-de-suivi-des-patients-atteints-du-cancer","status":"publish","type":"page","link":"https:\/\/visium360.fr\/index.php\/notre-plateforme-de-suivi-des-patients-atteints-du-cancer\/","title":{"rendered":"GEORGES \u2013 Simplifier et fiabiliser le suivi du parcours apr\u00e8s-cancer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3625\" class=\"elementor elementor-3625\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02b25ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02b25ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-976d967\" data-id=\"976d967\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-819e94f elementor-widget elementor-widget-spacer\" data-id=\"819e94f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc922b aleft elementor-widget elementor-widget-wgl-double-headings\" data-id=\"8bc922b\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__subtitle\"><span>NOS PLATEFORMES<\/span><\/div><h2 class=\"dbl__title-wrapper\"><span class=\"dbl__title\">Automatisation du Plan Personnalis\u00e9 Apr\u00e8s-Cancer (PPAC)\n<\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94cb888 elementor-widget elementor-widget-text-editor\" data-id=\"94cb888\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Une solution num\u00e9rique d\u00e9di\u00e9e aux h\u00f4pitaux et \u00e9tablissements de sant\u00e9 pour automatiser la gestion du Plan Personnalis\u00e9 Apr\u00e8s-Cancer (PPAC), garantir la conformit\u00e9 r\u00e9glementaire et faciliter la coordination entre les professionnels de sant\u00e9.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9b468c elementor-widget elementor-widget-spacer\" data-id=\"c9b468c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dac1c43 elementor-widget elementor-widget-text-editor\" data-id=\"dac1c43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>GEORGES est une application m\u00e9tier d\u00e9velopp\u00e9e par <strong data-start=\"976\" data-end=\"989\">Visium360<\/strong> pour accompagner les \u00e9tablissements de sant\u00e9 dans la mise en \u0153uvre du <strong data-start=\"1060\" data-end=\"1101\">Plan Personnalis\u00e9 Apr\u00e8s-Cancer (PPAC)<\/strong>, une obligation fix\u00e9e par l\u2019Institut National du Cancer (INCa).<\/p><p><br \/>La plateforme permet d\u2019automatiser la cr\u00e9ation, la transmission et le suivi du PPAC, \u00e0 partir des informations disponibles dans le dossier patient.<\/p><p data-start=\"1330\" data-end=\"1545\">En centralisant les donn\u00e9es et en simplifiant les \u00e9changes entre m\u00e9decins, infirmiers et coordinateurs, <strong data-start=\"1434\" data-end=\"1505\">GEORGES contribue \u00e0 un suivi plus fluide, plus s\u00fbr et plus conforme<\/strong> pour les patients atteints de cancer.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40613fb elementor-widget elementor-widget-spacer\" data-id=\"40613fb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd29eeb elementor-widget elementor-widget-spacer\" data-id=\"cd29eeb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a933cd6\" data-id=\"a933cd6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b2859c elementor-widget elementor-widget-spacer\" data-id=\"8b2859c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3a6bf8 elementor-widget elementor-widget-wgl-image-animate\" data-id=\"e3a6bf8\" data-element_type=\"widget\" data-widget_type=\"wgl-image-animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-image-animate\"><div class=\"img-layer_image-wrapper up_down\" style=\"z-index: 1\">\n                <div class=\"img-layer_item\" style=\"transform: translate(0%, 0%);\">\n                    <div class=\"img-layer_image\" style=\"animation-duration: 0s;\">\n                        <img decoding=\"async\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2025\/10\/VisuGeorges.png\" alt=\"VisuGeorges\" \/>\n                    <\/div>\n                <\/div>\n            <\/div> <div class=\"img-layer_image-wrapper left_right\" style=\"z-index: 1\">\n                <div class=\"img-layer_item\" style=\"transform: translate(0%, 0%);\">\n                    <div class=\"img-layer_image\" style=\"animation-duration: 3s;\">\n                        <img decoding=\"async\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/03\/Group10.png\" alt=\"Group10\" \/>\n                    <\/div>\n                <\/div>\n            <\/div> <div class=\"img-layer_image-wrapper left_right\" style=\"z-index: 1\">\n                <div class=\"img-layer_item\" style=\"transform: translate(0%, 0%);\">\n                    <div class=\"img-layer_image\" style=\"animation-duration: 4s;\">\n                        <img decoding=\"async\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/03\/Group9.png\" alt=\"Group9\" \/>\n                    <\/div>\n                <\/div>\n            <\/div> <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32a7d1a elementor-widget elementor-widget-spacer\" data-id=\"32a7d1a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e2b303 elementor-widget elementor-widget-text-editor\" data-id=\"3e2b303\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p data-start=\"2524\" data-end=\"2686\">GEORGES a \u00e9t\u00e9 con\u00e7u <strong data-start=\"2544\" data-end=\"2597\">en collaboration avec des professionnels de sant\u00e9<\/strong> et est actuellement en phase de validation aupr\u00e8s de plusieurs \u00e9tablissements pilotes.<\/p><p data-start=\"2693\" data-end=\"2869\">Plus d\u2019une dizaine d\u2019h\u00f4pitaux publics et priv\u00e9s ont d\u00e9j\u00e0 manifest\u00e9 leur int\u00e9r\u00eat pour la solution, qui vise \u00e0 devenir un <strong data-start=\"2813\" data-end=\"2868\">outil de r\u00e9f\u00e9rence national pour la gestion du PPAC<\/strong>.<\/p><p data-start=\"3073\" data-end=\"3187\">Vous souhaitez participer \u00e0 la phase pilote ou en savoir plus sur la solution GEORGES ?<\/p><p data-start=\"3073\" data-end=\"3187\">Contactez-nous pour une pr\u00e9sentation d\u00e9taill\u00e9e et un retour d\u2019exp\u00e9rience d\u2019\u00e9tablissements partenaires.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd706f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd706f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81fdb16\" data-id=\"81fdb16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e44b38 elementor-widget elementor-widget-spacer\" data-id=\"6e44b38\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca18bcf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca18bcf\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9cdb6f0\" data-id=\"9cdb6f0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc06231 elementor-widget elementor-widget-spacer\" data-id=\"dc06231\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3fd907c\" data-id=\"3fd907c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51b430d elementor-widget elementor-widget-spacer\" data-id=\"51b430d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58026a6 aleft elementor-widget elementor-widget-wgl-double-headings\" data-id=\"58026a6\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__subtitle\"><span>AVANTAGES<\/span><\/div><h3 class=\"dbl__title-wrapper\"><span class=\"dbl__title\">Les points forts de Georges<\/span><\/h3><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-825ecbf elementor-view-stacked aleft has-font elementor-widget-icon-box wgl-icon-box elementor-shape-circle elementor-widget elementor-widget-wgl-info-box\" data-id=\"825ecbf\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a  class=\"wgl-infobox  wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-correct\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"wgl-infobox_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span style=\"color: #ff6600;\"><strong>Automatisation du PPAC<\/strong><\/span><br \/><em>G\u00e9n\u00e9ration automatique du Plan Personnalis\u00e9 Apr\u00e8s-Cancer \u00e0 partir des donn\u00e9es m\u00e9dicales disponibles, selon les mod\u00e8les d\u00e9finis par l\u2019INCa.<\/em><\/p><\/div><\/div><\/div><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8120a64 elementor-view-stacked aleft has-font elementor-widget-icon-box wgl-icon-box elementor-shape-circle elementor-widget elementor-widget-wgl-info-box\" data-id=\"8120a64\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a  class=\"wgl-infobox  wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-correct\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"wgl-infobox_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span style=\"color: #ff6600;\"><strong>Simplicit\u00e9 et rapidit\u00e9 d\u2019utilisation<\/strong><\/span><br \/><em>Un outil intuitif qui r\u00e9duit consid\u00e9rablement le temps de saisie et le risque d\u2019erreurs.<\/em><\/p><\/div><\/div><\/div><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa5c78f elementor-view-stacked aleft has-font elementor-widget-icon-box wgl-icon-box elementor-shape-circle elementor-widget elementor-widget-wgl-info-box\" data-id=\"aa5c78f\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a  class=\"wgl-infobox  wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-correct\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"wgl-infobox_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span style=\"color: #ff6600;\"><strong>Coordination renforc\u00e9e<\/strong><\/span><br \/><em>Facilite le partage d\u2019informations entre m\u00e9decins, infirmiers, coordinateurs et secr\u00e9tariats.<\/em><\/p><\/div><\/div><\/div><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb12792 elementor-view-stacked aleft has-font elementor-widget-icon-box wgl-icon-box elementor-shape-circle elementor-widget elementor-widget-wgl-info-box\" data-id=\"bb12792\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a  class=\"wgl-infobox  wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-correct\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"wgl-infobox_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span style=\"color: #ff6600;\"><strong>Conformit\u00e9 r\u00e9glementaire<\/strong><\/span><br \/><em>Respect des exigences INCa et des protocoles institutionnels.<\/em><\/p><\/div><\/div><\/div><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f85bde9 elementor-view-stacked aleft has-font elementor-widget-icon-box wgl-icon-box elementor-shape-circle elementor-widget elementor-widget-wgl-info-box\" data-id=\"f85bde9\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a  class=\"wgl-infobox  wgl-layout-left\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-correct\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"wgl-infobox_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox_content\"><p><span style=\"color: #ff6600;\"><strong>S\u00e9curit\u00e9 et tra\u00e7abilit\u00e9 des donn\u00e9es<\/strong><\/span><br \/><em>Donn\u00e9es h\u00e9berg\u00e9es sur des serveurs HDS (H\u00e9bergement Donn\u00e9es de Sant\u00e9), garantissant confidentialit\u00e9 et fiabilit\u00e9.<\/em><\/p><\/div><\/div><\/div><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b10615 elementor-widget elementor-widget-spacer\" data-id=\"6b10615\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa9658e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa9658e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df884fd\" data-id=\"df884fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bc8e0b elementor-widget elementor-widget-spacer\" data-id=\"7bc8e0b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c7354b elementor-widget elementor-widget-wgl-flipbox\" data-id=\"8c7354b\" data-element_type=\"widget\" data-widget_type=\"wgl-flipbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"wgl-flipbox type_flip_top\">\n            <div  class=\"wgl-flipbox_wrap\">\n                <div class=\"wgl-flipbox_front\">                        <h3 class=\"wgl-flipbox_title\">\u201cParce qu\u2019apr\u00e8s le traitement, le parcours continue.\u201d<\/h3><div class=\"wgl-flipbox_button-wrap\"><div class=\"wgl-flipbox_item-link button-read-more icon-position-left\"><i aria-hidden=\"true\" class=\"flaticon-long-next\"><\/i><span><\/span><\/div><\/div>                <\/div>\n                <div class=\"wgl-flipbox_back\">                        <div class=\"wgl-flipbox_content\"><p><strong>GEORGES simplifie la coordination m\u00e9dicale et place le patient au centre du suivi post-cancer.<\/strong><\/p><\/div>                <\/div>\n            <\/div>\n        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccafebd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ccafebd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bbeead1\" data-id=\"bbeead1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6685c944 elementor-widget elementor-widget-wgl-clients\" data-id=\"6685c944\" data-element_type=\"widget\" data-widget_type=\"wgl-clients.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-clients clearfix anim-ex_images_ver items-5\" data-carousel=\"yes\"><div class=\"wgl-carousel_wrapper\"><div id=zikzag_carousel_6a97b43656fe4 class=\"wgl-carousel pagination_line_circle pag_align_center\"><div class=\"wgl-carousel_slick\" data-slick='{\"slidesToShow\":5,\"slidesToScroll\":1,\"infinite\":true,\"variableWidth\":false,\"autoplay\":true,\"autoplaySpeed\":\"3000\",\"speed\":300,\"arrows\":false,\"dots\":true,\"adaptiveHeight\":false,\"responsive\":[{\"breakpoint\":1400,\"settings\":{\"slidesToShow\":4,\"slidesToScroll\":1}},{\"breakpoint\":1024,\"settings\":{\"slidesToShow\":3,\"slidesToScroll\":1}},{\"breakpoint\":768,\"settings\":{\"slidesToShow\":2,\"slidesToScroll\":1}}]}'><div class=\"clients_image\"><div class=\"image_wrapper\"><img decoding=\"async\" class=\"hover_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/XtWVg0vz_400x400.jpg\" alt=\"XtWVg0vz_400x400\" \/><img decoding=\"async\" class=\"main_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/XtWVg0vz_400x400-copie.jpg\" alt=\"XtWVg0vz_400x400 copie\" \/><\/div><\/div><div class=\"clients_image\"><div class=\"image_wrapper\"><img decoding=\"async\" class=\"hover_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2025\/10\/CGFL.png\" alt=\"CGFL\" \/><img decoding=\"async\" class=\"main_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2025\/10\/CGFL-NB.png\" alt=\"CGFL NB\" \/><\/div><\/div><div class=\"clients_image\"><div class=\"image_wrapper\"><img decoding=\"async\" class=\"hover_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/te\u0301le\u0301chargement.png\" alt=\"te\u0301le\u0301chargement\" \/><img decoding=\"async\" class=\"main_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/te\u0301le\u0301chargement-copie.png\" alt=\"te\u0301le\u0301chargement copie\" \/><\/div><\/div><div class=\"clients_image\"><div class=\"image_wrapper\"><img decoding=\"async\" class=\"hover_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/Logo_du_CHU_de_Limoges.png\" alt=\"Logo_du_CHU_de_Limoges\" \/><img decoding=\"async\" class=\"main_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/Logo_du_CHU_de_Limoges-copie.png\" alt=\"Logo_du_CHU_de_Limoges copie\" \/><\/div><\/div><div class=\"clients_image\"><div class=\"image_wrapper\"><img decoding=\"async\" class=\"hover_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/LogoSherpaSante-1.png\" alt=\"LogoSherpaSante-1\" \/><img decoding=\"async\" class=\"main_image\" src=\"https:\/\/visium360.fr\/wp-content\/uploads\/2020\/12\/LogoSherpaSante.png\" alt=\"LogoSherpaSante\" \/><\/div><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NOS PLATEFORMES Automatisation du Plan Personnalis\u00e9 Apr\u00e8s-Cancer (PPAC) Une solution num\u00e9rique d\u00e9di\u00e9e aux h\u00f4pitaux et \u00e9tablissements de sant\u00e9 pour automatiser la gestion du Plan Personnalis\u00e9 Apr\u00e8s-Cancer (PPAC), garantir la conformit\u00e9 r\u00e9glementaire et faciliter la coordination entre les professionnels de sant\u00e9. GEORGES est une application m\u00e9tier d\u00e9velopp\u00e9e par Visium360 pour accompagner les \u00e9tablissements de sant\u00e9 dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3399,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3625","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/pages\/3625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3625"}],"version-history":[{"count":67,"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/pages\/3625\/revisions"}],"predecessor-version":[{"id":6680,"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/pages\/3625\/revisions\/6680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/media\/3399"}],"wp:attachment":[{"href":"https:\/\/visium360.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}